{"id":1246,"count":1,"description":"","link":"https:\/\/consumidorligado.com.br\/blog\/tag\/pagamento-parcial\/","name":"pagamento parcial","slug":"pagamento-parcial","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/consumidorligado.com.br\/blog\/wp-json\/wp\/v2\/tags\/1246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consumidorligado.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/consumidorligado.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/consumidorligado.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=1246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}