{"id":131,"count":1,"description":"","link":"https:\/\/consumidorligado.com.br\/blog\/tag\/extra\/","name":"Extra","slug":"extra","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/consumidorligado.com.br\/blog\/wp-json\/wp\/v2\/tags\/131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consumidorligado.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/consumidorligado.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/consumidorligado.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}