{"id":294,"count":1,"description":"","link":"https:\/\/consumidorligado.com.br\/blog\/tag\/protecao-contra-chargeback\/","name":"prote\u00e7\u00e3o contra chargeback","slug":"protecao-contra-chargeback","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/consumidorligado.com.br\/blog\/wp-json\/wp\/v2\/tags\/294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consumidorligado.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/consumidorligado.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/consumidorligado.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}