{"id":689,"count":2,"description":"","link":"https:\/\/consumidorligado.com.br\/blog\/tag\/comprovantes-de-pagamento\/","name":"comprovantes de pagamento","slug":"comprovantes-de-pagamento","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/consumidorligado.com.br\/blog\/wp-json\/wp\/v2\/tags\/689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consumidorligado.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/consumidorligado.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/consumidorligado.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}